{"id":40384,"date":"2025-09-30T20:55:24","date_gmt":"2025-09-30T19:55:24","guid":{"rendered":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840.jpg"},"modified":"2025-09-30T20:55:24","modified_gmt":"2025-09-30T19:55:24","slug":"imgp7840","status":"inherit","type":"attachment","link":"https:\/\/www.coursedestaleines.ch\/a\/2025-matin-partie-2-par-roger-stettler\/imgp7840\/","title":{"rendered":"IMGP7840"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-40384","attachment","type-attachment","status-inherit","hentry","column","threecol"],"description":{"rendered":"<p class=\"attachment\"><a rel='attachment' href='https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"199\" height=\"300\" src=\"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-199x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-199x300.jpg 199w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-681x1024.jpg 681w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-768x1155.jpg 768w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-700x1053.jpg 700w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-332x499.jpg 332w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840.jpg 1000w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":1504,"file":"2025\/09\/IMGP7840.jpg","filesize":345542,"sizes":{"medium":{"file":"IMGP7840-199x300.jpg","width":199,"height":300,"filesize":19742,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-199x300.jpg"},"large":{"file":"IMGP7840-681x1024.jpg","width":681,"height":1024,"filesize":158750,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-681x1024.jpg"},"thumbnail":{"file":"IMGP7840-150x150.jpg","width":150,"height":150,"filesize":10299,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-150x150.jpg"},"medium_large":{"file":"IMGP7840-768x1155.jpg","width":768,"height":1155,"filesize":194508,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-768x1155.jpg"},"slider-thumb":{"file":"IMGP7840-1000x395.jpg","width":1000,"height":395,"filesize":98892,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-1000x395.jpg"},"blog-thumb":{"file":"IMGP7840-700x1053.jpg","width":700,"height":1053,"filesize":166467,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-700x1053.jpg"},"teaser-thumb":{"file":"IMGP7840-332x499.jpg","width":332,"height":499,"filesize":45895,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-332x499.jpg"},"gallery-1-thumb":{"file":"IMGP7840-432x432.jpg","width":432,"height":432,"filesize":50209,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-432x432.jpg"},"gallery-2-thumb":{"file":"IMGP7840-268x268.jpg","width":268,"height":268,"filesize":23019,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-268x268.jpg"},"gallery-3-thumb":{"file":"IMGP7840-268x164.jpg","width":268,"height":164,"filesize":16081,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-268x164.jpg"},"image-thumb":{"file":"IMGP7840-700x1053.jpg","width":700,"height":1053,"filesize":166467,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-700x1053.jpg"},"video-thumb":{"file":"IMGP7840-700x393.jpg","width":700,"height":393,"filesize":68279,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840-700x393.jpg"},"full":{"file":"IMGP7840.jpg","width":1000,"height":1504,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840.jpg"}},"image_meta":{"aperture":"8","credit":"","camera":"PENTAX KP","caption":"","created_timestamp":"1758972348","copyright":"","focal_length":"210","iso":"1600","shutter_speed":"0.0015625","title":"","orientation":"1","keywords":[]}},"post":40298,"source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7840.jpg","filename":"IMGP7840.jpg","filesize":345542,"_links":{"self":[{"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/media\/40384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/comments?post=40384"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":40298,"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/posts\/40298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}