{"id":40293,"date":"2025-09-30T20:50:56","date_gmt":"2025-09-30T19:50:56","guid":{"rendered":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752.jpg"},"modified":"2025-09-30T20:50:56","modified_gmt":"2025-09-30T19:50:56","slug":"imgp7752","status":"inherit","type":"attachment","link":"https:\/\/www.coursedestaleines.ch\/a\/2025-matin-partie-1-par-roger-stettler\/imgp7752\/","title":{"rendered":"IMGP7752"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-40293","attachment","type-attachment","status-inherit","hentry","column","threecol"],"description":{"rendered":"<p class=\"attachment\"><a rel='attachment' href='https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"199\" height=\"300\" src=\"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-199x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-199x300.jpg 199w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-681x1024.jpg 681w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-768x1155.jpg 768w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-700x1053.jpg 700w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-332x499.jpg 332w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752.jpg 1000w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":1504,"file":"2025\/09\/IMGP7752.jpg","filesize":218580,"sizes":{"medium":{"file":"IMGP7752-199x300.jpg","width":199,"height":300,"filesize":18617,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-199x300.jpg"},"large":{"file":"IMGP7752-681x1024.jpg","width":681,"height":1024,"filesize":109191,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-681x1024.jpg"},"thumbnail":{"file":"IMGP7752-150x150.jpg","width":150,"height":150,"filesize":9795,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-150x150.jpg"},"medium_large":{"file":"IMGP7752-768x1155.jpg","width":768,"height":1155,"filesize":131514,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-768x1155.jpg"},"slider-thumb":{"file":"IMGP7752-1000x395.jpg","width":1000,"height":395,"filesize":50984,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-1000x395.jpg"},"blog-thumb":{"file":"IMGP7752-700x1053.jpg","width":700,"height":1053,"filesize":113970,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-700x1053.jpg"},"teaser-thumb":{"file":"IMGP7752-332x499.jpg","width":332,"height":499,"filesize":37678,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-332x499.jpg"},"gallery-1-thumb":{"file":"IMGP7752-432x432.jpg","width":432,"height":432,"filesize":34060,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-432x432.jpg"},"gallery-2-thumb":{"file":"IMGP7752-268x268.jpg","width":268,"height":268,"filesize":18763,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-268x268.jpg"},"gallery-3-thumb":{"file":"IMGP7752-268x164.jpg","width":268,"height":164,"filesize":13054,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-268x164.jpg"},"image-thumb":{"file":"IMGP7752-700x1053.jpg","width":700,"height":1053,"filesize":113970,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-700x1053.jpg"},"video-thumb":{"file":"IMGP7752-700x393.jpg","width":700,"height":393,"filesize":38980,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752-700x393.jpg"},"full":{"file":"IMGP7752.jpg","width":1000,"height":1504,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752.jpg"}},"image_meta":{"aperture":"8","credit":"","camera":"PENTAX KP","caption":"","created_timestamp":"1758971711","copyright":"","focal_length":"350","iso":"1600","shutter_speed":"0.00125","title":"","orientation":"1","keywords":[]}},"post":40175,"source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2025\/09\/IMGP7752.jpg","filename":"IMGP7752.jpg","filesize":218580,"_links":{"self":[{"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/media\/40293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/comments?post=40293"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":40175,"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/posts\/40175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}