{"id":38857,"date":"2024-09-30T22:15:35","date_gmt":"2024-09-30T21:15:35","guid":{"rendered":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2.jpg"},"modified":"2024-09-30T22:15:35","modified_gmt":"2024-09-30T21:15:35","slug":"imgp6604-3","status":"inherit","type":"attachment","link":"https:\/\/www.coursedestaleines.ch\/a\/2024-apres-midi-par-roger-stettler\/imgp6604-3\/","title":{"rendered":"IMGP6604"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-38857","attachment","type-attachment","status-inherit","hentry","column","threecol"],"description":{"rendered":"<p class=\"attachment\"><a rel='attachment' href='https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-300x199.jpg 300w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-1024x681.jpg 1024w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-768x511.jpg 768w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-700x465.jpg 700w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-332x221.jpg 332w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2.jpg 1504w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1504,"height":1000,"file":"2024\/09\/IMGP6604-2.jpg","filesize":728455,"sizes":{"medium":{"file":"IMGP6604-2-300x199.jpg","width":300,"height":199,"filesize":23462,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-300x199.jpg"},"large":{"file":"IMGP6604-2-1024x681.jpg","width":1024,"height":681,"filesize":176408,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-1024x681.jpg"},"thumbnail":{"file":"IMGP6604-2-150x150.jpg","width":150,"height":150,"filesize":11213,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-150x150.jpg"},"medium_large":{"file":"IMGP6604-2-768x511.jpg","width":768,"height":511,"filesize":108953,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-768x511.jpg"},"slider-thumb":{"file":"IMGP6604-2-1140x395.jpg","width":1140,"height":395,"filesize":106949,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-1140x395.jpg"},"blog-thumb":{"file":"IMGP6604-2-700x465.jpg","width":700,"height":465,"filesize":94387,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-700x465.jpg"},"teaser-thumb":{"file":"IMGP6604-2-332x221.jpg","width":332,"height":221,"filesize":27682,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-332x221.jpg"},"gallery-1-thumb":{"file":"IMGP6604-2-432x432.jpg","width":432,"height":432,"filesize":55359,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-432x432.jpg"},"gallery-2-thumb":{"file":"IMGP6604-2-268x268.jpg","width":268,"height":268,"filesize":26278,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-268x268.jpg"},"gallery-3-thumb":{"file":"IMGP6604-2-268x164.jpg","width":268,"height":164,"filesize":18765,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-268x164.jpg"},"image-thumb":{"file":"IMGP6604-2-700x465.jpg","width":700,"height":465,"filesize":94387,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-700x465.jpg"},"video-thumb":{"file":"IMGP6604-2-700x393.jpg","width":700,"height":393,"filesize":80244,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2-700x393.jpg"},"full":{"file":"IMGP6604-2.jpg","width":1504,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2.jpg"}},"image_meta":{"aperture":"11","credit":"ROGER STETTLER","camera":"PENTAX K-3 II","caption":"","created_timestamp":"1727532879","copyright":"ROGER STETTLER","focal_length":"35","iso":"400","shutter_speed":"0.008","title":"","orientation":"1","keywords":[]}},"post":38773,"source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6604-2.jpg","filename":"IMGP6604-2.jpg","filesize":728455,"_links":{"self":[{"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/media\/38857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/comments?post=38857"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":38773,"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/posts\/38773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}