{"id":38848,"date":"2024-09-30T22:15:33","date_gmt":"2024-09-30T21:15:33","guid":{"rendered":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2.jpg"},"modified":"2024-09-30T22:15:33","modified_gmt":"2024-09-30T21:15:33","slug":"imgp6677-3","status":"inherit","type":"attachment","link":"https:\/\/www.coursedestaleines.ch\/a\/2024-apres-midi-par-roger-stettler\/imgp6677-3\/","title":{"rendered":"IMGP6677"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-38848","attachment","type-attachment","status-inherit","hentry","column","threecol"],"description":{"rendered":"<p class=\"attachment\"><a rel='attachment' href='https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"199\" height=\"300\" src=\"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-199x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-199x300.jpg 199w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-681x1024.jpg 681w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-768x1155.jpg 768w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-700x1053.jpg 700w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-332x499.jpg 332w, https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2.jpg 1000w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":1504,"file":"2024\/09\/IMGP6677-2.jpg","filesize":654950,"sizes":{"medium":{"file":"IMGP6677-2-199x300.jpg","width":199,"height":300,"filesize":18410,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-199x300.jpg"},"large":{"file":"IMGP6677-2-681x1024.jpg","width":681,"height":1024,"filesize":149025,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-681x1024.jpg"},"thumbnail":{"file":"IMGP6677-2-150x150.jpg","width":150,"height":150,"filesize":8518,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-150x150.jpg"},"medium_large":{"file":"IMGP6677-2-768x1155.jpg","width":768,"height":1155,"filesize":183499,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-768x1155.jpg"},"slider-thumb":{"file":"IMGP6677-2-1000x395.jpg","width":1000,"height":395,"filesize":76229,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-1000x395.jpg"},"blog-thumb":{"file":"IMGP6677-2-700x1053.jpg","width":700,"height":1053,"filesize":156643,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-700x1053.jpg"},"teaser-thumb":{"file":"IMGP6677-2-332x499.jpg","width":332,"height":499,"filesize":42901,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-332x499.jpg"},"gallery-1-thumb":{"file":"IMGP6677-2-432x432.jpg","width":432,"height":432,"filesize":43808,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-432x432.jpg"},"gallery-2-thumb":{"file":"IMGP6677-2-268x268.jpg","width":268,"height":268,"filesize":20036,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-268x268.jpg"},"gallery-3-thumb":{"file":"IMGP6677-2-268x164.jpg","width":268,"height":164,"filesize":12941,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-268x164.jpg"},"image-thumb":{"file":"IMGP6677-2-700x1053.jpg","width":700,"height":1053,"filesize":156643,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-700x1053.jpg"},"video-thumb":{"file":"IMGP6677-2-700x393.jpg","width":700,"height":393,"filesize":56222,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2-700x393.jpg"},"full":{"file":"IMGP6677-2.jpg","width":1000,"height":1504,"mime_type":"image\/jpeg","source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2.jpg"}},"image_meta":{"aperture":"9","credit":"ROGER STETTLER","camera":"PENTAX K-3 II","caption":"","created_timestamp":"1727535783","copyright":"ROGER STETTLER","focal_length":"85","iso":"400","shutter_speed":"0.008","title":"","orientation":"1","keywords":[]}},"post":38773,"source_url":"https:\/\/www.coursedestaleines.ch\/a\/wp-content\/uploads\/2024\/09\/IMGP6677-2.jpg","filename":"IMGP6677-2.jpg","filesize":654950,"_links":{"self":[{"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/media\/38848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/comments?post=38848"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":38773,"href":"https:\/\/www.coursedestaleines.ch\/a\/wp-json\/wp\/v2\/posts\/38773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}